{"id":10812,"date":"2026-05-30T17:09:53","date_gmt":"2026-05-30T17:09:53","guid":{"rendered":"http:\/\/www.maseual.com.mx\/web\/?p=10812"},"modified":"2026-05-30T17:10:03","modified_gmt":"2026-05-30T17:10:03","slug":"un-millon-de-pesos-mas-para-concluir-rehabilitacion-y-restauracion-de-parroquia-en-zacatepec","status":"publish","type":"post","link":"http:\/\/www.maseual.com.mx\/web\/2026\/05\/30\/un-millon-de-pesos-mas-para-concluir-rehabilitacion-y-restauracion-de-parroquia-en-zacatepec\/","title":{"rendered":"UN MILL\u00d3N DE PESOS M\u00c1S PARA CONCLUIR REHABILITACI\u00d3N Y RESTAURACI\u00d3N DE PARROQUIA EN ZACATEPEC"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por HUGO BARBERI RICO \/ MASEUAL<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zacatepec, Morelos, M\u00e9xico, 30 de mayo de 2026.- Tras una \u00faltima inversi\u00f3n estimada en aproximadamente un mill\u00f3n de pesos, concluye hoy con la inauguraci\u00f3n encabezada por el Obispo, Ram\u00f3n Castro Castro, la rehabilitaci\u00f3n total de la Parroquia dedicada a Santiago Ap\u00f3stol de Zacatepec.<br>Hasta la ma\u00f1ana de ayer continuaban los \u00faltimos trabajos de restauraci\u00f3n del retablo principal de uno de los edificios m\u00e1s representativos del municipio, con detalles que para el d\u00eda de hoy por la tarde ya estar\u00edan listos para la visita del principal representante de la fe cat\u00f3lica en el estado de Morelos.<br>El presb\u00edtero, Jos\u00e9 Trinidad Hern\u00e1ndez V\u00e1zquez, p\u00e1rroco del lugar, record\u00f3 que la feligres\u00eda cat\u00f3lica no solo se bas\u00f3 en rehabilitar lo estructural, sino en el sentido est\u00e9tico y religioso, por lo que lograron un cambio de forma y de fondo del retablo de Santiago Ap\u00f3stol.<br>\u201cHemos hecho el esfuerzo para que la parroquia tenga candiles, porque ten\u00eda unas luces un poquito improvisadas\u2026 se dise\u00f1aron tres candiles para esta parroquia\u2026\u201d, coment\u00f3 Hern\u00e1ndez V\u00e1zquez.<br>Record\u00f3 que despu\u00e9s del sismo de 2017 en el que el edificio tuvo diversas aver\u00edas en su estructura, im\u00e1genes colapsadas, plaf\u00f3n, aplanados, azulejos que se cayeron, etc., por lo que hubo una reparaci\u00f3n inicial, sin embargo, el p\u00e1rroco Trinidad Hern\u00e1ndez, a\u00f1adi\u00f3 que aunque se arregl\u00f3 la iglesia \u201cpero el retablo no se toc\u00f3, lo cubrimos con madera, porque \u2018Santiago Ap\u00f3stol\u2019 pesaba mucho y no lo pod\u00edamos bajar, de tal manera que solamente se cubri\u00f3 con madera, despu\u00e9s lo descubrimos, se limpi\u00f3, pero fueron apareciendo unas grietas profundas donde hab\u00eda tambi\u00e9n filtraciones de algunas piedras que cayeron y estaba rehabilitando el retablo e iba poco a poco haciendo que se pudiera caer, sobre todo las molduras. Esto lo descubrimos porque \u00edbamos a tocar el retablo de la \u2018Virgen de Guadalupe\u2019, que ten\u00eda unas florecitas que se est\u00e1n poniendo muy grises y siendo pan de oro no deber\u00eda de ser y por eso llamamos a este restaurador\u201d.<br>Inform\u00f3 que la restauraci\u00f3n del retablo, tuvo un costo de aproximadamente un mill\u00f3n de pesos, financiado por los mismos fieles, familias que aportaron bonos de 5 mil pesos, \u201chay m\u00e1s de 60 bonos familiares. Aparte hay donativos de feligreses de Zacatepec que viven en los Estados Unidos\u201d, precis\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por HUGO BARBERI RICO \/ MASEUAL Zacatepec, Morelos, M\u00e9xico, 30 de mayo de 2026.- Tras&#8230;<\/p>\n","protected":false},"author":3,"featured_media":10813,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-10812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"featured_image_urls":{"full":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/05\/Parroquia-Santiago-Apostol-Zac.jpg",1600,1200,false],"thumbnail":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/05\/Parroquia-Santiago-Apostol-Zac-150x150.jpg",150,150,true],"medium":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/05\/Parroquia-Santiago-Apostol-Zac-300x225.jpg",300,225,true],"medium_large":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/05\/Parroquia-Santiago-Apostol-Zac-768x576.jpg",640,480,true],"large":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/05\/Parroquia-Santiago-Apostol-Zac-1024x768.jpg",640,480,true],"1536x1536":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/05\/Parroquia-Santiago-Apostol-Zac-1536x1152.jpg",1536,1152,true],"2048x2048":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/05\/Parroquia-Santiago-Apostol-Zac.jpg",1600,1200,false],"newsever-slider-full":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/05\/Parroquia-Santiago-Apostol-Zac-1280x845.jpg",1280,845,true],"newsever-featured":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/05\/Parroquia-Santiago-Apostol-Zac-1024x768.jpg",1024,768,true],"newsever-medium":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/05\/Parroquia-Santiago-Apostol-Zac-720x475.jpg",720,475,true]},"author_info":{"display_name":"Hugo Barberi Rico","author_link":"http:\/\/www.maseual.com.mx\/web\/author\/maseual\/"},"category_info":"<a href=\"http:\/\/www.maseual.com.mx\/web\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","tag_info":"Noticias","comment_count":"1","_links":{"self":[{"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/posts\/10812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/comments?post=10812"}],"version-history":[{"count":1,"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/posts\/10812\/revisions"}],"predecessor-version":[{"id":10814,"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/posts\/10812\/revisions\/10814"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/media\/10813"}],"wp:attachment":[{"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/media?parent=10812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/categories?post=10812"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/tags?post=10812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}