{"id":11045,"date":"2026-07-15T21:27:10","date_gmt":"2026-07-15T21:27:10","guid":{"rendered":"http:\/\/www.maseual.com.mx\/web\/?p=11045"},"modified":"2026-07-15T21:27:14","modified_gmt":"2026-07-15T21:27:14","slug":"matematicas-y-lectura-clave-para-futuras-generaciones","status":"publish","type":"post","link":"http:\/\/www.maseual.com.mx\/web\/2026\/07\/15\/matematicas-y-lectura-clave-para-futuras-generaciones\/","title":{"rendered":"MATEM\u00c1TICAS Y LECTURA: CLAVE PARA FUTURAS GENERACIONES"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por ALEJANDRO C\u00c1RDENAS SAN ANTONIO \/ MASEUAL<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuernavaca, Morelos, M\u00e9xico, 15 de julio de 2026.- <strong>Se van de vacaciones 322 mil 535 alumnos de nivel b\u00e1sico en la entidad. Pero hay un reto permanente que comparten autoridades educativas y padres de familia: conseguir que los alumnos eleven el dominio de las matem\u00e1ticas y la comprensi\u00f3n lectora.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Y es que este asunto va m\u00e1s all\u00e1 de la escuela, est\u00e1 dentro de la casa tambi\u00e9n.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estas competencias b\u00e1sicas en el futuro del alumno influyen de manera directa en su desarrollo personal, sus oportunidades laborales y su capacidad para participar plenamente en una sociedad cada vez m\u00e1s tecnol\u00f3gica y basada en el conocimiento.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nada m\u00e1s hay que recordar los siguientes datos para obligarnos a retomar la actuaci\u00f3n: en el a\u00f1o 2022, seg\u00fan los resultados del Programa para la Evaluaci\u00f3n Internacional de Estudiantes PISA, una prueba que mide el desempe\u00f1o de estudiantes de 15 a\u00f1os en todo el mundo y es coordinada por la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3micos OCDE, los alumnos mexicanos obtuvieron un promedio de 395 puntos en matem\u00e1ticas y 415 puntos en comprensi\u00f3n lectora, ubic\u00e1ndose por debajo de la media internacional que es de 472 y 476 puntos respectivamente, y ocurre que estos indicadores se encuentran en niveles similares desde hace 20 a\u00f1os.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Las escuelas de nivel b\u00e1sico estar\u00e1n cerradas por semanas, pero eso no significa dejar de seguir aprendiendo. En las casas hay que estimular y motivar el inter\u00e9s por el conocimiento.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hay un par de datos relevantes que se deben de corregir. Uno es que dos de cada tres estudiantes, no alcanzan el Nivel 2 en matem\u00e1ticas. Es decir, este nivel representa las habilidades b\u00e1sicas necesarias para resolver problemas cotidianos simples, como interpretar un porcentaje, elaborar un presupuesto o comprender medidas.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El otro dato relevante que hay que enmendar desde la casa como el anterior, es la comprensi\u00f3n lectora, porque el 47 % de los estudiantes, tiene dificultades para identificar la idea principal de un texto o para distinguir entre un hecho y una opini\u00f3n.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El sistema educativo siempre enfrenta retos importantes \u2014como lo fue el cierre de escuelas durante la pandemia que sigue teniendo consecuencias y las innegables brechas socioecon\u00f3micas\u2014, pero una cosa es muy clara: el aprendizaje no depende exclusivamente de los profesores. Las familias tambi\u00e9n juegan un papel relevante.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Crear el h\u00e1bito de la lectura en casa, apoyar las tareas escolares, conversar sobre lo que los hijos leen o resolver problemas matem\u00e1ticos cotidianos, son acciones que refuerzan el trabajo que se realiza en las escuelas de nivel b\u00e1sico.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pa\u00edses que obtienen mejores resultados en PISA suelen combinar pol\u00edticas educativas estables con una mayor participaci\u00f3n de las familias y una valoraci\u00f3n social del esfuerzo acad\u00e9mico. Es decir, se respeta y dignifica la responsabilidad de los maestros al frente de un aula.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En M\u00e9xico, se debe de crear nuevamente conciencia en estos aspectos para que de manera integral se mejoren estas competencias b\u00e1sicas. Es una tarea compartida entre escuelas, familias, autoridades y la sociedad en general. Nadie ha dicho que la responsabilidad de educar recae solamente de un lado.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para enfrentar un mundo globalizado, es necesario contar con s\u00f3lidas habilidades en matem\u00e1ticas y lectura porque eso a la larga da mejores oportunidades a quienes ser\u00e1n las futuras generaciones, permite acceso a estudios superiores, empleos de mayor calidad y mayor capacidad.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;Aunque no se perciba en lo inmediato, elevar el dominio de las matem\u00e1ticas y la comprensi\u00f3n lectora genera los h\u00e1bitos para adaptarse y participar en los inevitables y vertiginosos cambios de escalada mundial.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contribuye adem\u00e1s, a reducir la desigualdad y fortalecer el desarrollo del pa\u00eds.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Es por eso que superar estos indicadores de hace 20 a\u00f1os, requiere acciones sostenidas como fortalecer la educaci\u00f3n inicial y b\u00e1sica, mejorar la formaci\u00f3n y el apoyo a los docentes, y promover la participaci\u00f3n activa de las familias.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los resultados de PISA 2022 \u2014 bien analizados\u2014, ofrecen una oportunidad para nuevamente reflexionar y programar acciones y no solo en las escuelas de nivel b\u00e1sico, sino en casa durante estas vacaciones.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El aprendizaje de matem\u00e1ticas y lectura es clave para el futuro de los j\u00f3venes y aunque se dude, una de las mejores inversiones para la sociedad en general.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por ALEJANDRO C\u00c1RDENAS SAN ANTONIO \/ MASEUAL Cuernavaca, Morelos, M\u00e9xico, 15 de julio de 2026.-&#8230;<\/p>\n","protected":false},"author":3,"featured_media":11046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-11045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion"],"featured_image_urls":{"full":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/07\/Escritura-matematica.jpg",600,455,false],"thumbnail":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/07\/Escritura-matematica-150x150.jpg",150,150,true],"medium":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/07\/Escritura-matematica-300x228.jpg",300,228,true],"medium_large":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/07\/Escritura-matematica.jpg",600,455,false],"large":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/07\/Escritura-matematica.jpg",600,455,false],"1536x1536":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/07\/Escritura-matematica.jpg",600,455,false],"2048x2048":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/07\/Escritura-matematica.jpg",600,455,false],"newsever-slider-full":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/07\/Escritura-matematica.jpg",600,455,false],"newsever-featured":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/07\/Escritura-matematica.jpg",600,455,false],"newsever-medium":["http:\/\/www.maseual.com.mx\/web\/wp-content\/uploads\/2026\/07\/Escritura-matematica.jpg",600,455,false]},"author_info":{"display_name":"Hugo Barberi Rico","author_link":"http:\/\/www.maseual.com.mx\/web\/author\/maseual\/"},"category_info":"<a href=\"http:\/\/www.maseual.com.mx\/web\/category\/opinion\/\" rel=\"category tag\">Opini\u00f3n<\/a>","tag_info":"Opini\u00f3n","comment_count":"0","_links":{"self":[{"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/posts\/11045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/comments?post=11045"}],"version-history":[{"count":1,"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/posts\/11045\/revisions"}],"predecessor-version":[{"id":11047,"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/posts\/11045\/revisions\/11047"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/media\/11046"}],"wp:attachment":[{"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/media?parent=11045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/categories?post=11045"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.maseual.com.mx\/web\/wp-json\/wp\/v2\/tags?post=11045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}